{"id":551,"date":"2020-09-23T21:03:03","date_gmt":"2020-09-23T19:03:03","guid":{"rendered":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/?p=551"},"modified":"2020-10-07T19:37:27","modified_gmt":"2020-10-07T17:37:27","slug":"die-nachbarin","status":"publish","type":"post","link":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/2020\/09\/23\/die-nachbarin\/","title":{"rendered":"Die Nachbarin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Nachbarin &#8211; Thriller von Carolin Corcoran<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich will ehrlich zu Ihnen sein. Das Buch hat mir nicht gefallen &#8211; rein gar nicht. Es ist vielumworben und erhielt auch Lob. Mich hat es nicht erreicht.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/blogger.randomhouse.de\/content\/edition\/cover\/350px\/9783453580800.jpg\" alt=\"Die Nachbarin\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Der Klappentext ist noch spannend. Zwei Frauen, Wand an Wand in einem Wohnhaus. Die eine lebt ein scheinbar perfektes Leben mit ihrem Freund, die andere feiert ausgelassene Partys und ist einsam. Beide denken voneinander, dass die Welt der jeweils anderen so schillernd, so viel toller wie die eigene ist. Die d\u00fcnnen W\u00e4nde der Appartements erlauben eine sehr intime wenngleich anonyme N\u00e4he.  In der Innenseite dann noch der Hinweis von Harriet &#8222;sie wei\u00df nicht, was ich getan habe, sie hatte keine Ahnung zu was ich f\u00e4hig bin&#8220;. Das soll die Spannung erzeugen, die einen Thriller ausmacht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soweit das Versprechen. Der geneigte Leser startet in die Geschichte und stellt sehr schnell fest, dass es in den kommenden knapp 450 (!) Seiten immer nur zwei Perspektiven geben wird. Einmal Harriet, die Einsame, Party feiernde, neidvoll. Einmal Lexie, die mit Tom gl\u00fccklich zusammen lebt und sich sehnlichst Kinder w\u00fcnscht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von nun an schleppt sich Kapitel um Kapitel um den Neid der einen und den Kinderwunsch der anderen. Eines muss man der Autorin bescheinigen. Jedes Kapitel ist zwar inhaltlich nahezu gleich, Satzbau und Wortwahl aber nur selten Wiederholungen unterworfen. Man merkt also nicht sofort, dass es im Grunde nur um den Neid von Harriet und den Kinderwunsch von Lexie geht. Das dauert ein paar Seitenstr\u00e4nge &#8230;.. mit zunehmender Dauer &#8211; meine pers\u00f6nliche Schwelle ist immer so um die Seite 100, da muss es gefunkt haben &#8211; aber wird es z\u00e4h und m\u00fchsam. Harriet ist neidisch auf Lexie und Lexie will unbedingt schwanger werden, wird es aber nicht, was wiederum dazu f\u00fchrt, dass sie neidvoll an Harriets scheinbar gl\u00fccklichem Leben Anteil nimmt und sich in Ungl\u00fcck suhlt, w\u00e4hrend Harriet zu ihrem Neid nun auch noch ein paar Gemeinheiten gesellt und sich an Lexies Briefkasten und sp\u00e4ter an ihrem Freund Tom zu schaffen macht. Ab diesem Moment wird dann zum mantra-artigen Kinderwunsch auf der einen (Lexie), der mantra-artige Wunsch Tom besitzen zu wollen auf der anderen Seite (Harriet) in die Geschichte eingeflochten &#8211; was freilich eine kleine neue Nuance, aber nicht wirklich eine thriller-artig aufb\u00e4umende Spannung darstellt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Leser darf nun weiter Kapitel im Wechsel durchleben. Harriet will Tom. Lexie will ein Kind. Keiner ist gl\u00fccklich und Harriet hat schon ganz schlimme Dinge getan, von denen niemand etwas ahnt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese schlimmen Dinge schimmern gegen Ende des Buches etwas hervor und unternehmen den Versuch, die vorangegangene schleppende Handlung zu erkl\u00e4ren, so rechte Spannung mag dennoch nicht aufkommen, erst im Finale der letzten vielleicht 60-70 Seiten wird vielleicht aus dem Lesefunken etwas Glut und man so will &#8211; ist man nun schon soweit fortgeschritten, dann doch wissen zu wollen, wie es ausgeht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fazit<\/strong>: alles in allem f\u00fcr mich kein Lesetipp. Kein Thriller, zu schal, viel zu viele F\u00fcllkapitel.  Kinderlose Leser mit Kinderwunsch werden auf den ersten 250 Seiten entnervt die Segel streichen. Der Versuch eine Psychopathin zu skizzieren, mag f\u00fcr das reale Leben zutreffend sein, im Thriller Genre ist er meines Erachtens mi\u00dflungen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*** (c) Udo Kewitsch, Sept20 ***<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Nachbarin &#8211; Thriller von Carolin Corcoran Ich will ehrlich zu Ihnen sein. Das Buch hat mir nicht gefallen &#8211; rein gar nicht. Es ist vielumworben und erhielt auch Lob. Mich hat es nicht erreicht. Der Klappentext ist noch spannend. Zwei Frauen, Wand an Wand in einem Wohnhaus. Die eine lebt ein scheinbar perfektes Leben [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[78],"tags":[113,87,114],"class_list":["post-551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books","tag-buchbesprechung","tag-buecher","tag-thriller"],"_links":{"self":[{"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/posts\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/comments?post=551"}],"version-history":[{"count":3,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/posts\/551\/revisions"}],"predecessor-version":[{"id":555,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/posts\/551\/revisions\/555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/media\/553"}],"wp:attachment":[{"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/media?parent=551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/categories?post=551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.udomittendrin.de\/udomittendrin\/wordpress\/wp-json\/wp\/v2\/tags?post=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}